{"id":1,"count":3,"description":"","link":"https:\/\/academia.utp.edu.co\/bioecos\/category\/sin-categoria\/","name":"Sin categor\u00eda","slug":"sin-categoria","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/academia.utp.edu.co\/bioecos\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/academia.utp.edu.co\/bioecos\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/academia.utp.edu.co\/bioecos\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/academia.utp.edu.co\/bioecos\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}