{"id":9,"date":"2026-04-06T16:18:23","date_gmt":"2026-04-06T21:18:23","guid":{"rendered":"https:\/\/academia.utp.edu.co\/sdei\/?page_id=9"},"modified":"2026-05-11T10:04:15","modified_gmt":"2026-05-11T15:04:15","slug":"diversidad-y-educacion-inclusiva","status":"publish","type":"page","link":"https:\/\/academia.utp.edu.co\/sdei\/","title":{"rendered":"Diversidad y educaci\u00f3n inclusiva"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light wp-duotone-rgb64096-rgb210121255-1\" style=\"margin-top:0;padding-top:48px;padding-right:48px;padding-bottom:48px;padding-left:48px;min-height:50vh;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" class=\"wp-block-cover__image-background wp-image-12 size-large\" alt=\"\" src=\"http:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-30 has-background-dim\" style=\"background-color:#ceabaa\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group alignwide is-layout-constrained wp-container-core-group-is-layout-e555385e wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-white-color has-text-color\" style=\"margin-bottom:10px;font-size:clamp(36px, 6vw, 72px);font-style:normal;font-weight:700;letter-spacing:0px;line-height:1.05;text-transform:uppercase\">Diversidad y Educaci\u00f3n Inclusiva<\/h2>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color\" style=\"margin-top:0;font-size:clamp(18px, 3vw, 30px);font-weight:500;line-height:1.3\">Licenciaturas en Educaci\u00f3n B\u00e1sica Primaria y Educaci\u00f3n Infantil<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"max-width:1000px;margin:0 auto;padding:24px 20px 40px 20px;text-align:center\">\n  <div style=\"font-size:clamp(36px,6vw,70px);line-height:1;color:#3d4b63;margin-bottom:10px\">\u201c<\/div>\n  \n  <p style=\"margin:0 0 18px 0;font-size:clamp(20px,2.6vw,24px);line-height:1.6;font-style:italic;font-weight:600;color:#3d4b63\">\n    \u201cColombia est\u00e1 enferma de mismidad, y solo la provocaci\u00f3n y multiplicaci\u00f3n del encuentro con lo diferente podr\u00eda evitar que se perpet\u00fae el ciclo de nuestras violencias cuyo origen tal vez sea, en \u00faltima instancia, el miedo a ese extra\u00f1o cualquiera y m\u00faltiple, convertido en monstruo por la distancia que hemos interpuesto para no verlo y, por tanto, irrespetarlo.\u201d\n  <\/p>\n\n  <p style=\"margin:0;font-size:clamp(18px,2vw,18px);line-height:1.4;font-style:italic;font-weight:700;color:#D279FF\">\n    Pedro Adri\u00e1n Zuluaga (2020, p.39)\n  <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-container-core-group-is-layout-0805d2c6 wp-block-group-is-layout-constrained\" id=\"lineas-investigacion\" style=\"padding-top:30px;padding-right:24px;padding-bottom:30px;padding-left:24px\">\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-default\" style=\"background-color:#9d55b1;color:#9d55b1\" \/>\n\n\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong><strong>L\u00edneas de Investigaci\u00f3n<\/strong><\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" alt=\"\" class=\"wp-image-12\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Interculturalidad<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" alt=\"\" class=\"wp-image-12\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Curr\u00edculo y perspectivas de g\u00e9nero<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" alt=\"\" class=\"wp-image-12\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Discapacidad<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" alt=\"\" class=\"wp-image-12\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Lenguaje y justicia social<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" alt=\"\" class=\"wp-image-12\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Diversidades<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background is-layout-constrained wp-container-core-group-is-layout-85ae6cfc wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:40px;padding-right:24px;padding-bottom:40px;padding-left:24px\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2353cbd2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Objetivo del Semillero<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-center\">El prop\u00f3sito principal de este espacio es plantear y desarrollar propuestas investigativas en el campo de la diversidad y la educaci\u00f3n inclusiva. A trav\u00e9s de ello, se busca aportar al desarrollo de competencias investigativas; as\u00ed como, la transformaci\u00f3n de las pr\u00e1cticas pedag\u00f3gicas del profesorado en formaci\u00f3n en los distintos contextos y niveles escolares.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>\u00bfPor qu\u00e9 un semillero en Diversidad y Educaci\u00f3n Inclusiva?<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2353cbd2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center\">En el marco de los procesos de formaci\u00f3n de los futuros docentes de las Licenciaturas de Educaci\u00f3n Infantil y Educaci\u00f3n B\u00e1sica Primaria de la Universidad Tecnol\u00f3gica de Pereira, se busca desarrollar, en ellos, la capacidad para formular e implementar proyectos de investigaci\u00f3n que permitan indagar sobre posibles soluciones a problemas educativos de la regi\u00f3n. En este sentido, la creaci\u00f3n de este semillero responde al reto que afronta el contexto de la formaci\u00f3n inicial del profesorado: desarrollar en los futuros maestros la capacidad no solo de leer, pensar, cuestionar e interpretar la realidad hist\u00f3rica y social, sino de asumir un posicionamiento \u00e9tico y pol\u00edtico en favor de la justicia social.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center\">Actualmente, la diversidad es considerada un asunto problem\u00e1tico, no por las diferencias propias de los seres humanos, sino por la valoraci\u00f3n desigual que se hace de ellas. A pesar de los discursos de vanguardia, en los contextos educativos persiste la idea de una escuela y un estudiantado homog\u00e9neo y uniforme, donde las diferencias no son tenidas en cuenta ni respetadas. Para dar respuesta a esta situaci\u00f3n, los organismos de gobernanza internacional y nacional han propuesto pol\u00edticas y normativas enmarcadas en la Educaci\u00f3n Inclusiva. Si bien, este enfoque promueve el acceso, participaci\u00f3n y aprendizaje de todo el estudiantado (Ainscow, 2002), su foco se orienta a las poblaciones que \u201ctradicionalmente han sido excluidos de las oportunidades educativas\u201d (UNESCO; 2017, p.12). Con ello, se asocia la \u00abdiferencia\u00bb con una desventaja y se perpet\u00faa la discriminaci\u00f3n y exclusi\u00f3n de \u00abel otro\u00bb en el aula. Por esto, se hace necesario problematizar este panorama y fomentar el respeto a la diversidad desde la posibilidad de conocer, mirar, escuchar y entender la historia del otro de forma genuina.<\/p>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:36px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-container-core-group-is-layout-0805d2c6 wp-block-group-is-layout-constrained\" style=\"padding-top:30px;padding-right:24px;padding-bottom:30px;padding-left:24px\">\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Proyectos en curso<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" alt=\"\" class=\"wp-image-12\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Acordes Diversos: un di\u00e1logo de saberes interculturales mediados por la m\u00fasica en la construcci\u00f3n de identidad cultural y reconocimiento del otro en B\u00e1sica Primaria<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" alt=\"\" class=\"wp-image-12\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Dachi Daberaina Benacha Aprendei Matematica. Articulaci\u00f3n de los juegos tradicionales ind\u00edgenas como estrategia para el aprendizaje matem\u00e1tico, de los estudiantes de b\u00e1sica primaria de una comunidad Ember\u00e1 Cham\u00ed<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" alt=\"\" class=\"wp-image-12\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\">\u00d1ugpamanga yachaykunaua yachaykuspa Aprender desde el Origen<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background is-layout-constrained wp-container-core-group-is-layout-85ae6cfc wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:40px;padding-right:24px;padding-bottom:40px;padding-left:24px\">\n<div style=\"height:44px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"publicaciones-semillero\"><strong>Publicaciones del Semillero<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"600\" src=\"http:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Semillero-Inclusion-Publicaciones-Nuestras-Voces-2022.jpg\" alt=\"\" class=\"wp-image-140\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Semillero-Inclusion-Publicaciones-Nuestras-Voces-2022.jpg 960w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Semillero-Inclusion-Publicaciones-Nuestras-Voces-2022-300x188.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Semillero-Inclusion-Publicaciones-Nuestras-Voces-2022-768x480.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Nuestras Voces: Una apuesta pedag\u00f3gica para la participaci\u00f3n en los procesos de aprendizaje de los estudiantes emberas. 2022.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/hdl.handle.net\/11059\/14321\" target=\"_blank\" rel=\"noreferrer noopener\">Ver publicaci\u00f3n<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"600\" src=\"http:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Semillero-Inclusion-Publicaciones-Nuestras-Voces-2023.jpg\" alt=\"\" class=\"wp-image-141\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Semillero-Inclusion-Publicaciones-Nuestras-Voces-2023.jpg 960w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Semillero-Inclusion-Publicaciones-Nuestras-Voces-2023-300x188.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Semillero-Inclusion-Publicaciones-Nuestras-Voces-2023-768x480.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Nuestras voces: un estudio de caso sobre la participaci\u00f3n en los procesos de aprendizaje de estudiantes emberas. 2023. Editorial Universidad Tecnol\u00f3gica de Pereira.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--3\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/hdl.handle.net\/11059\/14937\" target=\"_blank\" rel=\"noreferrer noopener\">Ver publicaci\u00f3n<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:6px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Galer\u00eda fotogr\u00e1fica del Semillero<\/h3>\n\n\n\n<div class=\"alignnormal\">[metaslider id=\u00bb143&#8243;]<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background is-layout-constrained wp-container-core-group-is-layout-85ae6cfc wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:40px;padding-right:24px;padding-bottom:40px;padding-left:24px\">\n<div style=\"height:44px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Eventos en los que ha participado como Ponente<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>III Congreso cognici\u00f3n y formaci\u00f3n de maestros Encuentros Regionales y Nacionales de Semilleros de Investigaci\u00f3n (2021).<\/li>\n\n\n\n<li>Encuentro de Semilleros de Investigaci\u00f3n de la Facultad de Ciencias de la Educaci\u00f3n (2021).<\/li>\n\n\n\n<li>IV Bienal Latinoamericana y Caribe\u00f1a en primera infancia, ni\u00f1ez y Juventud.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>Desigualdades, diversidades y desplazamientos (2021).<\/li>\n\n\n\n<li>II Congreso Internacional en Curriculum e Identidades Culturales (2021).<\/li>\n\n\n\n<li>Encuentro Departamental de Semilleros de Investigaci\u00f3n, Nodo Risaralda (2021, 2022, 2023).<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li>Encuentro Regional de Semilleros de Investigaci\u00f3n del Eje Cafetero y Valle \u2013 RREDSI (2021).<\/li>\n\n\n\n<li>Congreso Internacional de Semilleros de Investigaci\u00f3n-Educaci\u00f3n-Tecnolog\u00eda CISIET (2023).<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:44px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:6px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"integrantes\"><strong><strong>Proyectos realizados<\/strong><\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" alt=\"\" class=\"wp-image-12\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Nuestras voces. Perspectivas sobre la participaci\u00f3n en los procesos de ense\u00f1anza y aprendizaje de los estudiantes Embera Cham\u00ed Del Resguardo Kurmad\u00f3 vinculados al nivel de B\u00e1sica Primaria en dos instituciones educativas urbanas del municipio de Pereira.<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-background is-layout-constrained wp-container-core-group-is-layout-3bcd2578 wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg\" alt=\"\" class=\"wp-image-12\" srcset=\"https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1024x576.jpg 1024w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-300x169.jpg 300w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-768x432.jpg 768w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion-1536x864.jpg 1536w, https:\/\/academia.utp.edu.co\/sdei\/files\/2026\/04\/Banner-Semillero-Inclusion.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Manos que hablan: Un an\u00e1lisis a la participaci\u00f3n de las y los estudiantes sordos de una instituci\u00f3n educativa de la ciudad de Pereira.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-wide\" style=\"margin-top:0;margin-bottom:0;background-color:#904fb1;color:#904fb1\" \/>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"integrantes\"><strong>Integrantes del Semillero de Investigaci\u00f3n<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Martha Luc\u00eda Garz\u00f3n Osorio<\/td><td>Tutor<\/td><\/tr><tr><td>Jhonier Stiven G\u00f3mez Ruiz<\/td><td>Estudiante L\u00edder<\/td><\/tr><tr><td>Daniel Andr\u00e9s Ceballos Garc\u00eda<\/td><td>Cotutor<\/td><\/tr><tr><td>Angela Gabriela Medina Su\u00e1rez<\/td><td>Cotutor<\/td><\/tr><tr><td>Jefferson Mart\u00ednez Santa<\/td><td>Cotutor<\/td><\/tr><tr><td>Gustavo Adolfo Montes Bedoya<\/td><td>Cotutor<\/td><\/tr><tr><td>Lilibeth Villadiego D\u00edaz<\/td><td>Cotutor<\/td><\/tr><tr><td>Jhan Carlos Siagama Nengarave<\/td><td>Estudiante<\/td><\/tr><tr><td>Karen Sofia Cuaspud Pantoja<\/td><td>Estudiante<\/td><\/tr><tr><td>Angie Tatiana Escobar Termal<\/td><td>Estudiante<\/td><\/tr><tr><td>Hilary Valencia Zapata<\/td><td>Estudiante<\/td><\/tr><tr><td>Jairo Hernan Revelo Chasoy<\/td><td>Estudiante<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Lista actualizada a 30 de marzo de 2026.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background is-layout-constrained wp-container-core-group-is-layout-85ae6cfc wp-block-group-is-layout-constrained\" style=\"background-color:#faefff;padding-top:40px;padding-right:24px;padding-bottom:40px;padding-left:24px\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2353cbd2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong><strong>\u00c1mbitos Probl\u00e9micos<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-center\">El semillero orienta sus investigaciones bas\u00e1ndose en el an\u00e1lisis de varios \u00e1mbitos probl\u00e9micos actuales:<\/p>\n\n\n\n<p>El derecho a una educaci\u00f3n con calidad y sin discriminaci\u00f3n, entendiendo que los grupos excluidos requieren una respuesta educativa clara para superar su situaci\u00f3n de vulnerabilidad. (ONU; 1990, 1993, 1994; Unesco, 2000, 2003; OEI, 2010, MEN 2017, 2021).<\/p>\n\n\n\n<p>Se valora te\u00f3ricamente y desde los discursos la educaci\u00f3n inclusiva, pero desde las pr\u00e1cticas de ense\u00f1anza no se hace explicita (Herrera y Melo, 2016; Restrepo, 2016; Madero, 2017; Gajardo, 2020). Esto conlleva a la permanencia de pr\u00e1cticas pedag\u00f3gicas integracionistas que no valoran las diferencias y que desencadenan barreras para el aprendizaje, propiciando fen\u00f3menos como la deserci\u00f3n escolar o el acoso (Su\u00e1rez, 2020; Carretero y Nolasco, 2020; Vernikoff et al., 2022; Ben-Ayed, 2025). Esto, porque se sigue relacionando la diversidad con el d\u00e9ficit y la vulnerabilidad, desconociendo las diferencias de los escolares en toda su dimensi\u00f3n (Druker, 2020; Skliar, 2018, Davis, 2023).<\/p>\n\n\n\n<p>Las concepciones mismas de los docentes sobre la diversidad, que deben transformarse para dejar de ser una barrera educativa y dar paso a culturas institucionales incluyentes centradas en el respeto (Pacifico et al., 2021; Paetsch et al.; 2023). Esto, dado que concepciones configuradas en pr\u00e1cticas de ense\u00f1anza y aprendizaje homog\u00e9nea, inciden en los significados, actitudes y pr\u00e1cticas de aula en relaci\u00f3n con el abordaje de la diversidad (Nogales, 2018; \u00c1lamo, 2018).<\/p>\n\n\n\n<p class=\"has-text-align-center\">Para abordar estas problem\u00e1ticas, el semillero entiende la diversidad, desde una perspectiva \u00e9tico-cr\u00edtica (Levinas, 2000; Contreras, 20218; Skliar, 2017; 2020) como una construcci\u00f3n simb\u00f3lica y relacional que propicia un encuentro de acogida y respeto a las m\u00faltiples diferencias presentes en el aula. Asimismo, asume la educaci\u00f3n inclusiva Un enfoque que permite garantizar la presencia, aprendizaje, participaci\u00f3n y promoci\u00f3n de todas y todos a una educaci\u00f3n de calidad, en la cual se reflexione sobre las inequidades e injusticias que enfrentan quienes, por sus diferencias, han experimentado m\u00faltiples formas de violencia. (Blanco, 2016; Ainscow, 2016; Echeita, 2018; Ocampo, 2022).<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2353cbd2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Metodolog\u00eda de Trabajo<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-center\">El funcionamiento del semillero se articula mediante las siguientes din\u00e1micas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lectura y an\u00e1lisis de documentos.<\/li>\n\n\n\n<li>Tutor\u00eda individual brindada por parte del asesor.<\/li>\n\n\n\n<li>Trabajo colaborativo y de construcci\u00f3n grupal.<\/li>\n\n\n\n<li>Encuentros para la socializaci\u00f3n de avances, as\u00ed como para la revisi\u00f3n y ajustes de los proyectos de investigaci\u00f3n.<\/li>\n\n\n\n<li>Uso de TIC, incluyendo carpetas compartidas y encuentros virtuales.<\/li>\n\n\n\n<li>Encuentros de asesores para la unificaci\u00f3n de criterios en relaci\u00f3n con los enfoques te\u00f3ricos y metodol\u00f3gicos asumidos.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>Actividades y Proyecciones<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-left\">A corto y mediano plazo, se espera que los miembros del semillero se involucran en las siguientes actividades formativas y acad\u00e9micas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vinculaci\u00f3n de nuevos proyectos de investigaci\u00f3n: Promoviendo activamente la investigaci\u00f3n formativa en los estudiantes de pregrado.<\/li>\n\n\n\n<li>Conformaci\u00f3n de una comunidad de aprendizaje: Orientada al desarrollo de competencias conceptuales, procedimentales y actitudinales en temas de pedagog\u00eda, diversidad y educaci\u00f3n inclusiva.<\/li>\n\n\n\n<li>Participaci\u00f3n en eventos acad\u00e9micos y cient\u00edficos: Para debatir y ampliar las reflexiones del grupo a nivel externo.<\/li>\n\n\n\n<li>Presentaci\u00f3n de hallazgos y escritura acad\u00e9mica: Redacci\u00f3n y presentaci\u00f3n de art\u00edculos de reflexi\u00f3n te\u00f3rica o investigativa en revistas, y la producci\u00f3n acad\u00e9mica de cap\u00edtulos de libro, cartillas y gu\u00edas.<\/li>\n\n\n\n<li>B\u00fasqueda de recursos: Participaci\u00f3n en diferentes convocatorias de financiaci\u00f3n para los proyectos de investigaci\u00f3n.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c \u201cColombia est\u00e1 enferma de mismidad, y solo la provocaci\u00f3n y multiplicaci\u00f3n del encuentro con lo diferente podr\u00eda evitar que se perpet\u00fae el ciclo de nuestras violencias cuyo origen tal [&hellip;]<\/p>\n","protected":false},"author":1970,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"normal-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/academia.utp.edu.co\/sdei\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/academia.utp.edu.co\/sdei\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/academia.utp.edu.co\/sdei\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/academia.utp.edu.co\/sdei\/wp-json\/wp\/v2\/users\/1970"}],"replies":[{"embeddable":true,"href":"https:\/\/academia.utp.edu.co\/sdei\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":77,"href":"https:\/\/academia.utp.edu.co\/sdei\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":199,"href":"https:\/\/academia.utp.edu.co\/sdei\/wp-json\/wp\/v2\/pages\/9\/revisions\/199"}],"wp:attachment":[{"href":"https:\/\/academia.utp.edu.co\/sdei\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}